{"id":1373,"date":"2022-09-13T22:17:04","date_gmt":"2022-09-14T01:17:04","guid":{"rendered":"http:\/\/190.102.40.72\/~attualeb\/?p=1373"},"modified":"2022-09-29T13:18:33","modified_gmt":"2022-09-29T16:18:33","slug":"limpador-forense-e-acumulacoes","status":"publish","type":"post","link":"https:\/\/attualebrasil.com.br\/es\/limpador-forense-e-acumulacoes\/","title":{"rendered":"Limpiador Forense y Acumulaciones"},"content":{"rendered":"<p>En estas andanzas de la vida, perdemos la cuenta de la cantidad de servicios realizados por AttualeBrasil.<\/p>\n<p>Entramos en lugares oscuros, sin luz, sucios, contaminados, sin vida.<\/p>\n<p>No todos aceptan la muerte, una ciudad como S\u00e3o Paulo, por ejemplo, tiene sus misterios, en alg\u00fan departamento o casa hay un acumulador, hay alguien que vive solo y solo se recuerda cuando el olor a descomposici\u00f3n del cuerpo llama la atenci\u00f3n de alguien.<\/p>\n<p>No tenemos miedo de entrar a estos lugares, tenemos respeto, hab\u00eda vida all\u00ed.<br \/>\nMuchos lugares sin condiciones higi\u00e9nicas, pronto se reconoce el abandono, pronto se observa la depresi\u00f3n al ver objetos dejados en los rincones. solo imaginar que alguien viviera en ese ambiente, un ambiente triste, sucio y sin condiciones sanitarias para vivir, a excepci\u00f3n de los insectos. La riqueza que ten\u00edan estaba en objetos de los que era dif\u00edcil desprenderse, ese reloj de pared que ya no marca el tiempo, la mesa vieja que seguro tuvo varias cenas, esas monta\u00f1as de juguetes y ositos de peluche que recuerdan la infancia que yace en el pasado. . .<br \/>\nGuardas tantas cosas y de la nada aparecen personas extra\u00f1as y sacan todo, empacan todo, desechan todo, mueven tus libros, se separan documentos, abres la heladera y no se usa nada, abres la despensa y las conservas est\u00e1n caducadas, se no se consum\u00edan sino que se recog\u00edan.<\/p>\n<p>Hay ropa en el tendedero que por el tiempo est\u00e1 m\u00e1s que seca y tambi\u00e9n olvidada, la porcelana vieja viene a impresionar cuando le quitas el polvo.<\/p>\n<p>As\u00ed que tenemos que empezar a limpiar. Entra en juego ropa especial, mascarillas, guantes, botas, anteojos, bolsas de basura, cajas de cart\u00f3n para embalar, un basurero en la calle, un cami\u00f3n para llevar lo que hay que incinerar. Separar, limpiar, dejar, vaciar.<\/p>\n<p>Es entonces cuando no encontramos sangre y fluidos por todas partes, el olor a veces traspasa el filtro de la mascarilla, en cuyo caso es necesario cambiar y reforzar la seguridad. Las bacterias est\u00e1n en todas partes, est\u00e1n en el aire.<\/p>\n<p>Las larvas se mueven para entrar en metamorfosis, es algo aterrador, pero sabemos que hubo vida en ese lugar. Sabemos que la depresi\u00f3n es grave, sabemos que una decepci\u00f3n en el pasado puede traer consecuencias psicol\u00f3gicas en el futuro, sabemos que todo lo que es demasiado se interpone en el camino y no nos hace ning\u00fan bien.<\/p>\n<p>Estas personas que alguna vez acumularon alegr\u00eda, bondad, optimismo, hoy lamentablemente acumulan tristeza.<\/p>\n<p>Estas personas alguna vez estuvieron rodeadas de amigos y familiares, hoy lamentablemente mueren solos y olvidados.<\/p>\n<p>Estas personas alguna vez desearon tener a alguien, hoy prefieren estar a solas con sus secretos.<\/p>\n<p>Esas personas\u2026.<\/p>","protected":false},"excerpt":{"rendered":"<p>Nessas andan\u00e7as da vida, perdemos a conta da quantidade de servi\u00e7os realizados pela AttualeBrasil. Entramos em lugares escuros, apagados, sujos, contaminados, sem vida. Nem todos aceitam a morte, uma cidade como S\u00e3o Paulo por exemplo tem seus mist\u00e9rios, em algum apartamento ou casa h\u00e1 um acumulador, h\u00e1 algu\u00e9m vivendo sozinho (a) e s\u00f3 \u00e9 lembrado [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_angie_page":false,"page_builder":"","footnotes":""},"categories":[1],"tags":[142,141,140],"class_list":["post-1373","post","type-post","status-publish","format-standard","hentry","category-blog","tag-limpeza-cenas-de-crime","tag-limpeza-de-acumulacao","tag-limpeza-pos-morte-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.1 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Limpador Forense e acumula\u00e7\u00f5es | Attuale Brasil<\/title>\n<meta name=\"description\" content=\"Nessas andan\u00e7as da vida, perdemos a conta da quantidade de servi\u00e7os realizados pela AttualeBrasil. Entramos em lugares escuros, apagados, sujos,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/attualebrasil.com.br\/es\/limpador-forense-e-acumulacoes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Limpador Forense e acumula\u00e7\u00f5es\" \/>\n<meta property=\"og:description\" content=\"Nessas andan\u00e7as da vida, perdemos a conta da quantidade de servi\u00e7os realizados pela AttualeBrasil. Entramos em lugares escuros, apagados, sujos,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/attualebrasil.com.br\/es\/limpador-forense-e-acumulacoes\/\" \/>\n<meta property=\"og:site_name\" content=\"Attuale Brasil\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/attualebrasil.com.br\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-14T01:17:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-29T16:18:33+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/attualebrasil.com.br\\\/limpador-forense-e-acumulacoes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/attualebrasil.com.br\\\/limpador-forense-e-acumulacoes\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Limpador Forense e acumula\u00e7\u00f5es\",\"datePublished\":\"2022-09-14T01:17:04+00:00\",\"dateModified\":\"2022-09-29T16:18:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/attualebrasil.com.br\\\/limpador-forense-e-acumulacoes\\\/\"},\"wordCount\":449,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/attualebrasil.com.br\\\/#organization\"},\"keywords\":[\"limpeza cenas de crime\",\"limpeza de acumula\u00e7\u00e3o\",\"limpeza pos morte\"],\"articleSection\":[\"Blog\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/attualebrasil.com.br\\\/limpador-forense-e-acumulacoes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/attualebrasil.com.br\\\/limpador-forense-e-acumulacoes\\\/\",\"url\":\"https:\\\/\\\/attualebrasil.com.br\\\/limpador-forense-e-acumulacoes\\\/\",\"name\":\"Limpador Forense e acumula\u00e7\u00f5es | Attuale Brasil\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/attualebrasil.com.br\\\/#website\"},\"datePublished\":\"2022-09-14T01:17:04+00:00\",\"dateModified\":\"2022-09-29T16:18:33+00:00\",\"description\":\"Nessas andan\u00e7as da vida, perdemos a conta da quantidade de servi\u00e7os realizados pela AttualeBrasil. Entramos em lugares escuros, apagados, sujos,\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/attualebrasil.com.br\\\/limpador-forense-e-acumulacoes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/attualebrasil.com.br\\\/limpador-forense-e-acumulacoes\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/attualebrasil.com.br\\\/limpador-forense-e-acumulacoes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/attualebrasil.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Limpador Forense e acumula\u00e7\u00f5es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/attualebrasil.com.br\\\/#website\",\"url\":\"https:\\\/\\\/attualebrasil.com.br\\\/\",\"name\":\"Attuale Brasil\",\"description\":\"Limpeza p\u00f3s morte e Servi\u00e7os de Descontamina\u00e7\u00e3o \",\"publisher\":{\"@id\":\"https:\\\/\\\/attualebrasil.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/attualebrasil.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/attualebrasil.com.br\\\/#organization\",\"name\":\"Attuale Brasil\",\"url\":\"https:\\\/\\\/attualebrasil.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/attualebrasil.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/attualebrasil.com.br\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo-1.jpg\",\"contentUrl\":\"https:\\\/\\\/attualebrasil.com.br\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo-1.jpg\",\"width\":100,\"height\":100,\"caption\":\"Attuale Brasil\"},\"image\":{\"@id\":\"https:\\\/\\\/attualebrasil.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/attualebrasil.com.br\\\/\"]},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Limpador Forense e acumula\u00e7\u00f5es | Attuale Brasil","description":"Nessas andan\u00e7as da vida, perdemos a conta da quantidade de servi\u00e7os realizados pela AttualeBrasil. Entramos em lugares escuros, apagados, sujos,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/attualebrasil.com.br\/es\/limpador-forense-e-acumulacoes\/","og_locale":"es_ES","og_type":"article","og_title":"Limpador Forense e acumula\u00e7\u00f5es","og_description":"Nessas andan\u00e7as da vida, perdemos a conta da quantidade de servi\u00e7os realizados pela AttualeBrasil. Entramos em lugares escuros, apagados, sujos,","og_url":"https:\/\/attualebrasil.com.br\/es\/limpador-forense-e-acumulacoes\/","og_site_name":"Attuale Brasil","article_publisher":"https:\/\/www.facebook.com\/attualebrasil.com.br\/","article_published_time":"2022-09-14T01:17:04+00:00","article_modified_time":"2022-09-29T16:18:33+00:00","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/attualebrasil.com.br\/limpador-forense-e-acumulacoes\/#article","isPartOf":{"@id":"https:\/\/attualebrasil.com.br\/limpador-forense-e-acumulacoes\/"},"author":{"name":"","@id":""},"headline":"Limpador Forense e acumula\u00e7\u00f5es","datePublished":"2022-09-14T01:17:04+00:00","dateModified":"2022-09-29T16:18:33+00:00","mainEntityOfPage":{"@id":"https:\/\/attualebrasil.com.br\/limpador-forense-e-acumulacoes\/"},"wordCount":449,"commentCount":0,"publisher":{"@id":"https:\/\/attualebrasil.com.br\/#organization"},"keywords":["limpeza cenas de crime","limpeza de acumula\u00e7\u00e3o","limpeza pos morte"],"articleSection":["Blog"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/attualebrasil.com.br\/limpador-forense-e-acumulacoes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/attualebrasil.com.br\/limpador-forense-e-acumulacoes\/","url":"https:\/\/attualebrasil.com.br\/limpador-forense-e-acumulacoes\/","name":"Limpador Forense e acumula\u00e7\u00f5es | Attuale Brasil","isPartOf":{"@id":"https:\/\/attualebrasil.com.br\/#website"},"datePublished":"2022-09-14T01:17:04+00:00","dateModified":"2022-09-29T16:18:33+00:00","description":"Nessas andan\u00e7as da vida, perdemos a conta da quantidade de servi\u00e7os realizados pela AttualeBrasil. Entramos em lugares escuros, apagados, sujos,","breadcrumb":{"@id":"https:\/\/attualebrasil.com.br\/limpador-forense-e-acumulacoes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/attualebrasil.com.br\/limpador-forense-e-acumulacoes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/attualebrasil.com.br\/limpador-forense-e-acumulacoes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/attualebrasil.com.br\/"},{"@type":"ListItem","position":2,"name":"Limpador Forense e acumula\u00e7\u00f5es"}]},{"@type":"WebSite","@id":"https:\/\/attualebrasil.com.br\/#website","url":"https:\/\/attualebrasil.com.br\/","name":"Brasil actual","description":"Limpeza p\u00f3s morte e Servi\u00e7os de Descontamina\u00e7\u00e3o","publisher":{"@id":"https:\/\/attualebrasil.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/attualebrasil.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/attualebrasil.com.br\/#organization","name":"Brasil actual","url":"https:\/\/attualebrasil.com.br\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/attualebrasil.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/attualebrasil.com.br\/wp-content\/uploads\/2022\/05\/logo-1.jpg","contentUrl":"https:\/\/attualebrasil.com.br\/wp-content\/uploads\/2022\/05\/logo-1.jpg","width":100,"height":100,"caption":"Attuale Brasil"},"image":{"@id":"https:\/\/attualebrasil.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/attualebrasil.com.br\/"]},{"@type":"Person","@id":""}]}},"_links":{"self":[{"href":"https:\/\/attualebrasil.com.br\/es\/wp-json\/wp\/v2\/posts\/1373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/attualebrasil.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/attualebrasil.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/attualebrasil.com.br\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/attualebrasil.com.br\/es\/wp-json\/wp\/v2\/comments?post=1373"}],"version-history":[{"count":3,"href":"https:\/\/attualebrasil.com.br\/es\/wp-json\/wp\/v2\/posts\/1373\/revisions"}],"predecessor-version":[{"id":2401,"href":"https:\/\/attualebrasil.com.br\/es\/wp-json\/wp\/v2\/posts\/1373\/revisions\/2401"}],"wp:attachment":[{"href":"https:\/\/attualebrasil.com.br\/es\/wp-json\/wp\/v2\/media?parent=1373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/attualebrasil.com.br\/es\/wp-json\/wp\/v2\/categories?post=1373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/attualebrasil.com.br\/es\/wp-json\/wp\/v2\/tags?post=1373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}